{"id":2978,"date":"2022-06-06T09:41:27","date_gmt":"2022-06-06T07:41:27","guid":{"rendered":"https:\/\/pumble.com\/help\/?p=2978"},"modified":"2026-07-13T16:16:42","modified_gmt":"2026-07-13T14:16:42","slug":"manage-link-previews","status":"publish","type":"post","link":"https:\/\/pumble.com\/help\/fr\/workspace-administration\/workspace-settings\/manage-link-previews\/","title":{"rendered":"G\u00e9rer les aper\u00e7us de liens"},"content":{"rendered":"<div class=\"wp-block-custom-audience-tag audience-tag-box\"><span class=\"tag-title\">Qui peut utiliser cette fonctionnalit\u00e9 ?<\/span><div class=\"tag-rows\"><div class=\"tag-row\"><svg width=\"18\" height=\"18\" viewbox=\"0 0 24 24\" fill=\"none\"><mask id=\"mask-aud-final\" style=\"mask-type:alpha\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"24\"><rect width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask-aud-final)\"><path d=\"M12 12C10.9 12 9.95833 11.6083 9.175 10.825C8.39167 10.0417 8 9.1 8 8C8 6.9 8.39167 5.95833 9.175 5.175C9.95833 4.39167 10.9 4 12 4C13.1 4 14.0417 4.39167 14.825 5.175C15.6083 5.95833 16 6.9 16 8C16 9.1 15.6083 10.0417 14.825 10.825C14.0417 11.6083 13.1 12 12 12ZM4 20V17.2C4 16.6333 4.14583 16.1125 4.4375 15.6375C4.72917 15.1625 5.11667 14.8 5.6 14.55C6.63333 14.0333 7.68333 13.6458 8.75 13.3875C9.81667 13.1292 10.9 13 12 13C13.1 13 14.1833 13.1292 15.25 13.3875C16.3167 13.6458 17.3667 14.0333 18.4 14.55C18.8833 14.8 19.2708 15.1625 19.5625 15.6375C19.8542 16.1125 20 16.6333 20 17.2V20H4ZM6 18H18V17.2C18 17.0167 17.9542 16.85 17.8625 16.7C17.7708 16.55 17.65 16.4333 17.5 16.35C16.6 15.9 15.6917 15.5625 14.775 15.3375C13.8583 15.1125 12.9333 15 12 15C11.0667 15 10.1417 15.1125 9.225 15.3375C8.30833 15.5625 7.4 15.9 6.5 16.35C6.35 16.4333 6.22917 16.55 6.1375 16.7C6.04583 16.85 6 17.0167 6 17.2V18ZM12 10C12.55 10 13.0208 9.80417 13.4125 9.4125C13.8042 9.02083 14 8.55 14 8C14 7.45 13.8042 6.97917 13.4125 6.5875C13.0208 6.19583 12.55 6 12 6C11.45 6 10.9792 6.19583 10.5875 6.5875C10.1958 6.97917 10 7.45 10 8C10 8.55 10.1958 9.02083 10.5875 9.4125C10.9792 9.80417 11.45 10 12 10Z\" fill=\"black\" fill-opacity=\"0.87\"><\/path><\/g><\/svg><span>Propri\u00e9taire, Administrateur<\/span><\/div><div class=\"tag-row\"><svg width=\"18\" height=\"18\" viewbox=\"0 0 24 24\" fill=\"none\"><mask id=\"mask-flg-final\" style=\"mask-type:alpha\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"24\"><rect width=\"24\" height=\"24\" fill=\"#D9D9D9\"><\/rect><\/mask><g mask=\"url(#mask-flg-final)\"><path d=\"M5 21V4H14L14.4 6H20V16H13L12.6 14H7V21H5ZM14.65 14H18V8H12.75L12.35 6H7V12H14.25L14.65 14Z\" fill=\"black\" fill-opacity=\"0.87\"><\/path><\/g><\/svg><span>Disponible dans toutes les abonnements<\/span><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu'un membre partage un lien dans Pumble, les autres membres de l'espace de travail peuvent voir l'aper\u00e7u de cette page web. L'aper\u00e7u des liens peut \u00eatre d\u00e9sactiv\u00e9 pour une URL sp\u00e9cifique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour d\u00e9sactiver l'aper\u00e7u d'un site Web sp\u00e9cifique :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Survolez un lien partag\u00e9 dans une application de bureau<\/li>\n\n\n\n<li>Cliquez sur le bouton x dans le coin sup\u00e9rieur gauche<\/li>\n\n\n\n<li class=\"translation-block\">Le modal <strong>Bloquer l\u2019aper\u00e7u des liens<\/strong> s\u2019affiche<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"517\" height=\"338\" src=\"https:\/\/pumble.com\/help\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-19-at-16.38-1.png\" alt=\"\" class=\"wp-image-6608\" srcset=\"https:\/\/pumble.com\/help\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-19-at-16.38-1.png 517w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-19-at-16.38-1-300x196.png 300w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2023\/10\/Screenshot-2023-10-19-at-16.38-1-18x12.png 18w\" sizes=\"auto, (max-width: 517px) 100vw, 517px\" \/><\/figure>\n\n\n\n<p class=\"translation-block wp-block-paragraph translation-block\">Cochez la case <strong>Bloquer les aper\u00e7us de ce site Web \u00e0 l\u2019avenir<\/strong> et choisissez l\u2019une des options suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bloquer toutes les aper\u00e7us de ce site Web (bloquer toutes les aper\u00e7us de ce site Web) <\/li>\n\n\n\n<li>Bloquer toutes les aper\u00e7us de ce lien (bloquer toutes les aper\u00e7us de ce lien)<\/li>\n\n\n\n<li>Bloquer toutes les aper\u00e7us de ce sous-r\u00e9pertoire (bloquer les aper\u00e7us de liens du sous-r\u00e9pertoire URL) <\/li>\n<\/ul>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Cliquez sur <strong>\u00c9liminer et bloquer<\/strong> pour compl\u00e9ter l\u2019action.<\/p>\n\n\n\n<p class=\"translation-block wp-block-paragraph\">Dans l\u2019exemple : https:\/\/pumble.com\/help\/<strong>pumble-basics<\/strong>\/what-is-pumble\/, le texte en gras est un exemple de sous-r\u00e9pertoire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si cette option est coch\u00e9e, l'aper\u00e7u des liens vers les articles de cette section de l'aide de Pumble sera bloqu\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez consulter tous les liens bloqu\u00e9s en vous rendant dans l\u2019onglet \u00ab Pi\u00e8ces jointes \u00bb. Voici comment proc\u00e9der :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li class=\"translation-block\">Cliquez sur les <strong>trois points<\/strong> situ\u00e9s \u00e0 c\u00f4t\u00e9 du nom de l\u2019espace de travail<\/li>\n\n\n\n<li class=\"translation-block\">Survolez les <strong>Param\u00e8tres de l'espace de travail<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Cliquez sur <strong>Param\u00e8tres g\u00e9n\u00e9raux<\/strong><\/li>\n\n\n\n<li class=\"translation-block\">Cliquez sur l\u2019onglet <strong>Pi\u00e8ces jointes<\/strong><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"221\" src=\"https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/attachment-tab-1024x221.jpg\" alt=\"\" class=\"wp-image-13511\" style=\"aspect-ratio:4.63368384761248;width:583px;height:auto\" srcset=\"https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/attachment-tab-1024x221.jpg 1024w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/attachment-tab-300x65.jpg 300w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/attachment-tab-768x166.jpg 768w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/attachment-tab-18x4.jpg 18w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/attachment-tab.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading translation-block\">Aper\u00e7us des liens Plaky<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous ins\u00e9rez des liens vers des \u00e9l\u00e9ments de Plaky dans Pumble, vous pouvez passer la souris sur le lien pour afficher un aper\u00e7u de l\u2019\u00e9l\u00e9ment. L\u2019aper\u00e7u affichera tous les \u00e9l\u00e9ments importants de l\u2019\u00e9l\u00e9ment, tels que :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tableau<\/li>\n\n\n\n<li>Groupe d\u2019\u00e9l\u00e9ments<\/li>\n\n\n\n<li>Statut<\/li>\n\n\n\n<li>Responsables<\/li>\n\n\n\n<li>Tag<\/li>\n\n\n\n<li>Date d\u2019\u00e9ch\u00e9ance<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"945\" src=\"https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/image-1024x945.jpeg\" alt=\"\" class=\"wp-image-14226\" style=\"aspect-ratio:1.083608804321535;width:433px;height:auto\" srcset=\"https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/image-1024x945.jpeg 1024w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/image-300x277.jpeg 300w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/image-768x709.jpeg 768w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/image-13x12.jpeg 13w, https:\/\/pumble.com\/help\/wp-content\/uploads\/2022\/06\/image.jpeg 1036w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group related-articles\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Articles similaires<\/h3>\n\n\n\n<ul class=\"wp-block-list related-articles-list\">\n<li class=\"translation-block\"><a href=\"https:\/\/pumble.com\/help\/fr\/using-pumble\/messages\/send-and-read-messages\/\">Envoyer et lire des messages<\/a><\/li>\n\n\n\n<li class=\"translation-block\"><a href=\"https:\/\/pumble.com\/help\/using-pumble\/messages\/copy-link-to-message\/\">Copy Link to Message<\/a><\/li>\n<\/ul>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"When a member shares a link in Pumble, other workspace members are able to see t&#8230;","protected":false},"author":19,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_helpful_status":1,"_searchwp_excluded":"","footnotes":""},"categories":[60],"tags":[],"class_list":["post-2978","post","type-post","status-publish","format-standard","hentry","category-workspace-settings"],"acf":[],"featured_image_src":null,"author_info":{"display_name":"Tamara Radijevac","author_link":"https:\/\/pumble.com\/help\/fr\/author\/tamara\/"},"_links":{"self":[{"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/posts\/2978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/comments?post=2978"}],"version-history":[{"count":29,"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/posts\/2978\/revisions"}],"predecessor-version":[{"id":14227,"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/posts\/2978\/revisions\/14227"}],"wp:attachment":[{"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/media?parent=2978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/categories?post=2978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pumble.com\/help\/fr\/wp-json\/wp\/v2\/tags?post=2978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}